{"id":4953,"date":"2012-11-08T04:56:16","date_gmt":"2012-11-08T09:56:16","guid":{"rendered":"http:\/\/www.urbecom.com\/blog\/?p=4953"},"modified":"2012-11-07T08:01:49","modified_gmt":"2012-11-07T13:01:49","slug":"aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online","status":"publish","type":"post","link":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/","title":{"rendered":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online"},"content":{"rendered":"<p style=\"text-align: justify;\">Como ya <a href=\"http:\/\/www.urbecom.com\/blog\/ya-es-hora-de-preparar-la-navidad-en-tu-tienda-online\/\" target=\"_blank\">hicimos hace un par de d\u00edas<\/a>, vamos a ir d\u00e1ndote una serie de pautas por las que puedes dejarte guiar, aplic\u00e1ndolas por completo o adapt\u00e1ndolas a tu propia idea, de cara a iniciar <strong>una campa\u00f1a de navidad exitosa<\/strong>, y con exitosa nos referimos no solo a que te reporte los beneficios econ\u00f3micos que esperas, sino a que tambi\u00e9n deje un grato recuerdo en tus clientes.<\/p>\n<p style=\"text-align: justify;\"><a title=\"crear tienda online\" href=\"http:\/\/www.urbecom.com\" target=\"_blank\">Crear tienda online<\/a> puede suponer adaptarse a \u00e9pocas de ventas un poco fren\u00e9ticas, pero sin duda la experiencia te habr\u00e1 merecido la pena. Una <strong>buena campa\u00f1a de navidad<\/strong> puede suponer para tu <strong>tienda online<\/strong> el empuj\u00f3n que necesita para posicionarse en su sector y ganar la confianza de sus compradores. Su importancia va m\u00e1s all\u00e1 de conseguir ganar m\u00e1s dinero en este per\u00edodo, ya que si no se hace bien en la siguiente ocasi\u00f3n podemos no tener tanta suerte.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-4954\" title=\"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online\" src=\"http:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online.jpg\" alt=\"\" width=\"600\" height=\"511\" srcset=\"https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online.jpg 600w, https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online-300x255.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 aspectos, s\u00ed o s\u00ed, debemos tener en cuenta al enfrentarnos a una<strong> campa\u00f1a de navidad<\/strong>?. Varios y muy importantes:<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Control y previsi\u00f3n de stock.<\/strong>\u00a0 Debes adquirir la mercanc\u00eda que piensas vas a necesitar m\u00e1s, tanto las existencias de venta como el material que empleas para tu actividad cotidiana (consumibles inform\u00e1ticos, papel de envolver, lazos, cintas, tarjetas, folios, &#8230;) ya que al igual que ocurre contigo, tus proveedores han de servir m\u00e1s cantidades a m\u00e1s clientes y puede que se produzca una rotura de stock importante.\u00a0 Cr\u00e9enos al decirte que una <strong>campa\u00f1a de navidad<\/strong> en ciernes no es el mejor momento para aventurarse a buscar nuevos proveedores, ya que va a ser m\u00e1s dif\u00edcil negociar mejores tarifas o menores plazos de entrega, incluso se har\u00e1 complicado encontrar los productos que quieres porque ellos ya los habr\u00e1n reservado para sus propios clientes.<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Acordar y fijar fechas de entrega<\/strong>. Estas fechas van a ser un completo caos en lo que a <strong>expediciones de pedidos<\/strong> y entregas se refiere. Todos vais a estar tremendamente ocupados, incluidas las empresas de transporte.\u00a0 Negocia con tu transportista habitual los nuevos <strong>plazos de entrega<\/strong>, si es que estos van a sufrir variaciones por un volumen de trabajo muy superior.\u00a0 Es el momento de dejarlo todo bien atado para modificar por tu parte estas condiciones en tu sitio e informar a tus clientes de esta circunstancia temporal. Las sorpresas de \u00faltima hora no pueden producirse en plena campa\u00f1a de navidad ya que hay fechas en las que los pedidos deben estar entregados, son d\u00edas clave en este aspecto el 23 de diciembre y el 5 de enero.<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Adquirir los obsequios que vas a regalar a tus clientes<\/strong>. Muchas <strong>tiendas online<\/strong>, movidas por el esp\u00edritu generoso de estas fechas, buscan agasajar a sus clientes con un peque\u00f1o detalle que les haga sentirse especiales. Independientemente de lo que vayas a escoger finalmente debes asegurarte de que tu proveedor te podr\u00e1 servir la cantidad que necesitas y tendr\u00e1s que realizar el pedido con tiempo suficiente como para tenerlo en tu almac\u00e9n justo para comenzar a enviarlo con los primeros pedidos de la campa\u00f1a.\u00a0 Cuida bien este detalle, ya que si lo vas a anunciar en tu sitio ser\u00e1 algo con lo que de antemano cuenten tus clientes. Si algunos de ellos no lo pueden recibir se van a sentir decepcionados, por lo que vas a tener que compensar de alguna forma, con otro regalo o realizando el env\u00edo despu\u00e9s, pero esto puede suponerte un gasto extra.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Como ya hicimos hace un par de d\u00edas, vamos a ir d\u00e1ndote una serie de pautas por las que puedes dejarte guiar, aplic\u00e1ndolas por completo o adapt\u00e1ndolas a tu propia idea, de cara a iniciar una campa\u00f1a de navidad exitosa, y con exitosa nos referimos no solo a que te reporte los beneficios econ\u00f3micos que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[744,51,188,365],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online<\/title>\n<meta name=\"description\" content=\"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online\" \/>\n<meta property=\"og:description\" content=\"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de comercio electr\u00f3nico, Ecommerce y Marketing Online | urbeCOM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbecom\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-08T09:56:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-07T13:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbecom\" \/>\n<meta name=\"twitter:site\" content=\"@urbecom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/#organization\",\"name\":\"UrbeCOM Ecomercio S.L.\",\"url\":\"https:\/\/www.urbecom.com\/blog\/\",\"sameAs\":[\"https:\/\/es.pinterest.com\/Urbecom\/\",\"https:\/\/www.youtube.com\/user\/urbecom\",\"https:\/\/www.facebook.com\/urbecom\",\"https:\/\/twitter.com\/urbecom\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2019\/05\/Imagotipo800.png\",\"contentUrl\":\"https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2019\/05\/Imagotipo800.png\",\"width\":800,\"height\":800,\"caption\":\"UrbeCOM Ecomercio S.L.\"},\"image\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/#website\",\"url\":\"https:\/\/www.urbecom.com\/blog\/\",\"name\":\"Blog de comercio electr\u00f3nico, Ecommerce y Marketing Online | urbeCOM\",\"description\":\"Blog de urbeCOM donde encontrar\u00e1s informaci\u00f3n sobre el comercio electr\u00f3nico, c\u00f3mo crear una tienda online, c\u00f3mo vender en Internet y en Redes Sociales, Marketing online, etc.\",\"publisher\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.urbecom.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage\",\"url\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/\",\"name\":\"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online\",\"isPartOf\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/#website\"},\"datePublished\":\"2012-11-08T09:56:16+00:00\",\"dateModified\":\"2012-11-07T13:01:49+00:00\",\"description\":\"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa\",\"breadcrumb\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.urbecom.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/#\/schema\/person\/d7c213dd82e482dbd40a897ada31a39b\"},\"headline\":\"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online\",\"datePublished\":\"2012-11-08T09:56:16+00:00\",\"dateModified\":\"2012-11-07T13:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage\"},\"wordCount\":611,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.urbecom.com\/blog\/#organization\"},\"keywords\":[\"campa\u00f1as\",\"consejos\",\"navidad\",\"ventas\"],\"articleSection\":[\"Comercio Electr\u00f3nico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.urbecom.com\/blog\/#\/schema\/person\/d7c213dd82e482dbd40a897ada31a39b\",\"name\":\"Redaccion\",\"url\":\"https:\/\/www.urbecom.com\/blog\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online","description":"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/","og_locale":"es_ES","og_type":"article","og_title":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online","og_description":"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa","og_url":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/","og_site_name":"Blog de comercio electr\u00f3nico, Ecommerce y Marketing Online | urbeCOM","article_publisher":"https:\/\/www.facebook.com\/urbecom","article_published_time":"2012-11-08T09:56:16+00:00","article_modified_time":"2012-11-07T13:01:49+00:00","og_image":[{"url":"http:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2012\/11\/Aspectos-a-tener-en-cuenta-en-la-campa\u00f1a-de-navidad-de-una-tienda-online.jpg"}],"twitter_card":"summary_large_image","twitter_creator":"@urbecom","twitter_site":"@urbecom","twitter_misc":{"Escrito por":"Redaccion","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.urbecom.com\/blog\/#organization","name":"UrbeCOM Ecomercio S.L.","url":"https:\/\/www.urbecom.com\/blog\/","sameAs":["https:\/\/es.pinterest.com\/Urbecom\/","https:\/\/www.youtube.com\/user\/urbecom","https:\/\/www.facebook.com\/urbecom","https:\/\/twitter.com\/urbecom"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.urbecom.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2019\/05\/Imagotipo800.png","contentUrl":"https:\/\/www.urbecom.com\/blog\/wp-content\/uploads\/2019\/05\/Imagotipo800.png","width":800,"height":800,"caption":"UrbeCOM Ecomercio S.L."},"image":{"@id":"https:\/\/www.urbecom.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.urbecom.com\/blog\/#website","url":"https:\/\/www.urbecom.com\/blog\/","name":"Blog de comercio electr\u00f3nico, Ecommerce y Marketing Online | urbeCOM","description":"Blog de urbeCOM donde encontrar\u00e1s informaci\u00f3n sobre el comercio electr\u00f3nico, c\u00f3mo crear una tienda online, c\u00f3mo vender en Internet y en Redes Sociales, Marketing online, etc.","publisher":{"@id":"https:\/\/www.urbecom.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.urbecom.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage","url":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/","name":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online","isPartOf":{"@id":"https:\/\/www.urbecom.com\/blog\/#website"},"datePublished":"2012-11-08T09:56:16+00:00","dateModified":"2012-11-07T13:01:49+00:00","description":"Detalles que nunca pueden pasarse por alto si lo que buscamos es una campa\u00f1a de navidad fruct\u00edfera y exitosa","breadcrumb":{"@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.urbecom.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online"}]},{"@type":"Article","@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#article","isPartOf":{"@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage"},"author":{"@id":"https:\/\/www.urbecom.com\/blog\/#\/schema\/person\/d7c213dd82e482dbd40a897ada31a39b"},"headline":"Aspectos a tener en cuenta en la campa\u00f1a de navidad de una tienda online","datePublished":"2012-11-08T09:56:16+00:00","dateModified":"2012-11-07T13:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#webpage"},"wordCount":611,"commentCount":0,"publisher":{"@id":"https:\/\/www.urbecom.com\/blog\/#organization"},"keywords":["campa\u00f1as","consejos","navidad","ventas"],"articleSection":["Comercio Electr\u00f3nico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.urbecom.com\/blog\/aspectos-a-tener-en-cuenta-en-la-campana-de-navidad-de-una-tienda-online\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.urbecom.com\/blog\/#\/schema\/person\/d7c213dd82e482dbd40a897ada31a39b","name":"Redaccion","url":"https:\/\/www.urbecom.com\/blog\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/posts\/4953"}],"collection":[{"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/comments?post=4953"}],"version-history":[{"count":2,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/posts\/4953\/revisions"}],"predecessor-version":[{"id":4956,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/posts\/4953\/revisions\/4956"}],"wp:attachment":[{"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/media?parent=4953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/categories?post=4953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.urbecom.com\/blog\/wp-json\/wp\/v2\/tags?post=4953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}